{"id":128,"date":"2025-02-18T16:43:43","date_gmt":"2025-02-18T16:43:43","guid":{"rendered":"https:\/\/www.rollcom.fr\/skyroll\/?p=128"},"modified":"2025-02-25T19:38:09","modified_gmt":"2025-02-25T19:38:09","slug":"la-bataille-des-vitraux-de-notre-dame","status":"publish","type":"post","link":"https:\/\/www.rollcom.fr\/skyroll\/2025\/02\/18\/la-bataille-des-vitraux-de-notre-dame\/","title":{"rendered":"La bataille des vitraux de Notre Dame"},"content":{"rendered":"\n<p>La juridiction administrative aura \u00e0 se prononcer sur la d\u00e9cision du pr\u00e9sident de la R\u00e9publique d&rsquo;apporter sa petite touche personnelle \u00e0 la restauration de la cath\u00e9drale Notre Dame de Paris, par la mise en place de vitraux contemporains.<\/p>\n\n\n\n<p>Apr\u00e8s l\u2019incendie du 15 avril 2019 qui a ravag\u00e9 la cath\u00e9drale Notre-Dame de Paris, un vaste effort de financement a \u00e9t\u00e9 lanc\u00e9 pour sa reconstruction. Une <a href=\"https:\/\/www.legifrance.gouv.fr\/jorf\/id\/JORFTEXT000038843049\" data-type=\"link\" data-id=\"https:\/\/www.legifrance.gouv.fr\/jorf\/id\/JORFTEXT000038843049\" target=\"_blank\" rel=\"noreferrer noopener\">loi du 29 juillet 2019<\/a> a lanc\u00e9 une souscription nationale ouverte pour la conservation et la restauration de la cath\u00e9drale Notre-Dame de Paris plac\u00e9e sous la haute autorit\u00e9 du Pr\u00e9sident de la R\u00e9publique fran\u00e7aise.<\/p>\n\n\n\n<p>C&rsquo;est cette loi qui est invoqu\u00e9e par l&rsquo;association <a href=\"https:\/\/www.sitesetmonuments.org\/paris-notre-dame-vitraux-de-viollet-le-duc#pagination_liste_articles\" data-type=\"link\" data-id=\"https:\/\/www.sitesetmonuments.org\/paris-notre-dame-vitraux-de-viollet-le-duc#pagination_liste_articles\" target=\"_blank\" rel=\"noreferrer noopener\">Sites &amp; Monuments<\/a> pour faire obstacle \u00e0 la d\u00e9cision du pr\u00e9sident de la R\u00e9publique de remplacer les vitraux <strong>Viollet-le-Duc<\/strong> par des vitraux contemporains pour \u00ab\u00a0porter la marque du XXI\u00e8me si\u00e8cle\u00a0\u00bb (annonce lors d&rsquo;une visite du chantier le 8 d\u00e9cembre 2023). Les verri\u00e8res du XIX\u00e8me si\u00e8cle qui ont \u00e9t\u00e9 restaur\u00e9es seront d\u00e9mont\u00e9es et expos\u00e9es dans un futur mus\u00e9e d\u00e9di\u00e9 \u00e0 l&rsquo;histoire de la cath\u00e9drale. Le 18 d\u00e9cembre 2024, Emmanuel Macron et l\u2019archev\u00eaque de Paris ont <a href=\"https:\/\/www.beauxarts.com\/grand-format\/lartiste-claire-tabouret-choisie-pour-realiser-les-vitraux-contemporains-de-notre-dame\/\" data-type=\"link\" data-id=\"https:\/\/www.beauxarts.com\/grand-format\/lartiste-claire-tabouret-choisie-pour-realiser-les-vitraux-contemporains-de-notre-dame\/\" target=\"_blank\" rel=\"noreferrer noopener\">annonc\u00e9 avoir choisi l&rsquo;article Claire Tabouret<\/a> pour cr\u00e9er ces vitraux contemporains.  <br><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"200\" src=\"https:\/\/www.rollcom.fr\/skyroll\/wp-content\/uploads\/2025\/02\/leduc-vs-tabouret-.png\" alt=\"\" class=\"wp-image-203\" srcset=\"https:\/\/www.rollcom.fr\/skyroll\/wp-content\/uploads\/2025\/02\/leduc-vs-tabouret-.png 750w, https:\/\/www.rollcom.fr\/skyroll\/wp-content\/uploads\/2025\/02\/leduc-vs-tabouret--300x80.png 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption class=\"wp-element-caption\">Vitraux Leduc vs projet Tabouret<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Au grand damne de la tribune de l&rsquo;Art d\u00e9non\u00e7ant un manque d&rsquo;\u00e9gard pour le code du patrimoine. \u00ab\u00a0<em>Les vitraux n&rsquo;avaient pas \u00e9t\u00e9 touch\u00e9s par l&rsquo;incendie et sont class\u00e9s monuments historiques au m\u00eame titre que le monument (&#8230;) Ces verri\u00e8res n&rsquo;ont d&rsquo;int\u00e9r\u00eat qu&rsquo;in situ, en tant qu&rsquo;\u00e9l\u00e9ment \u00e0 part enti\u00e8re de l&rsquo;architecture [pens\u00e9e par Violet-Leduc}<\/em>\u00a0\u00bb \u00e9crit le fondateur du site, Didier Rkyner. <\/p>\n\n\n\n<p>Une s\u00e9rie d&rsquo;action en justice est pr\u00e9vue. La premi\u00e8re a \u00e9t\u00e9 initi\u00e9e devant le tribunal administratif de Paris et consiste \u00e0 <a href=\"https:\/\/www.sitesetmonuments.org\/Communique-Sites-Monuments-depose-un-premier-recours-contre-l-enlevement-des-vitraux-d-Eugene-Viollet-le-Duc-a-Notre-Dame\" data-type=\"link\" data-id=\"https:\/\/www.sitesetmonuments.org\/Communique-Sites-Monuments-depose-un-premier-recours-contre-l-enlevement-des-vitraux-d-Eugene-Viollet-le-Duc-a-Notre-Dame\" target=\"_blank\" rel=\"noreferrer noopener\">contester la comp\u00e9tence<\/a> de l&rsquo;\u00e9tablissement public charg\u00e9 de la conservation et de la restauration de la cath\u00e9drale Notre-Dame a organis\u00e9 le remplacement des vitraux. Cet \u00e9tablissement n&rsquo;aurait comp\u00e9tence \u00e0 agir que dans le cadre de la loi et du d\u00e9cret qui pr\u00e9voit une mission de conservation et de restauration de la cath\u00e9drale. L&rsquo;\u00e9tablissement public n&rsquo;aurait pas le droit d&rsquo;organiser le march\u00e9 de conception, r\u00e9alisation et pose de vitraux contemporains. <a href=\"https:\/\/www.latribunedelart.com\/un-premier-recours-pour-sauver-les-vitraux-de-viollet-le-duc\" data-type=\"link\" data-id=\"https:\/\/www.latribunedelart.com\/un-premier-recours-pour-sauver-les-vitraux-de-viollet-le-duc\">L&rsquo;association pr\u00e9voit par la suite de contester l&rsquo;arr\u00eat\u00e9 d&rsquo;autorisation de travaux d\u00e9livr\u00e9 par le pr\u00e9fet de Paris<\/a>. Elle pourrait aussi chercher sur le volet p\u00e9nal \u00e0 faire condamner l&rsquo;Etat pour d\u00e9tournement de fonds de la souscription nationale (on notera que le co\u00fbt des vitraux contemporains pourrait avoisiner 3,7 millions d&rsquo;euros). <\/p>\n\n\n\n<p>Il semble toutefois que <a href=\"https:\/\/www.latribunedelart.com\/vitraux-de-notre-dame-un-etablissement-public-peut-il-aller-contre-sa-mission\" data-type=\"link\" data-id=\"https:\/\/www.latribunedelart.com\/vitraux-de-notre-dame-un-etablissement-public-peut-il-aller-contre-sa-mission\" target=\"_blank\" rel=\"noreferrer noopener\">l&rsquo;invocation de l&rsquo;article 432-15 du code p\u00e9nal<\/a> qui punit toute personne d\u00e9positaire de l&rsquo;autorit\u00e9 publique de soustraire au public tout objet du domaine public soit vou\u00e9e \u00e0 l&rsquo;\u00e9chec. En effet, jamais il n&rsquo;a \u00e9t\u00e9 question de mettre en cause l\u00a0\u00bbacc\u00e8s au public des vitraux remplac\u00e9s. A suivre.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>La juridiction administrative aura \u00e0 se prononcer sur la d\u00e9cision du pr\u00e9sident de la R\u00e9publique d&rsquo;apporter sa petite touche personnelle \u00e0 la restauration de la <a class=\"mh-excerpt-more\" href=\"https:\/\/www.rollcom.fr\/skyroll\/2025\/02\/18\/la-bataille-des-vitraux-de-notre-dame\/\" title=\"La bataille des vitraux de Notre Dame\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":202,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[90,42,88],"class_list":["post-128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","tag-art","tag-droit","tag-droit-administratif"],"_links":{"self":[{"href":"https:\/\/www.rollcom.fr\/skyroll\/wp-json\/wp\/v2\/posts\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rollcom.fr\/skyroll\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rollcom.fr\/skyroll\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rollcom.fr\/skyroll\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rollcom.fr\/skyroll\/wp-json\/wp\/v2\/comments?post=128"}],"version-history":[{"count":3,"href":"https:\/\/www.rollcom.fr\/skyroll\/wp-json\/wp\/v2\/posts\/128\/revisions"}],"predecessor-version":[{"id":204,"href":"https:\/\/www.rollcom.fr\/skyroll\/wp-json\/wp\/v2\/posts\/128\/revisions\/204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rollcom.fr\/skyroll\/wp-json\/wp\/v2\/media\/202"}],"wp:attachment":[{"href":"https:\/\/www.rollcom.fr\/skyroll\/wp-json\/wp\/v2\/media?parent=128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rollcom.fr\/skyroll\/wp-json\/wp\/v2\/categories?post=128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rollcom.fr\/skyroll\/wp-json\/wp\/v2\/tags?post=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}